{"id":7017,"date":"2014-08-15T13:40:01","date_gmt":"2014-08-15T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2014\/08\/15\/sante-le-nigeria-prend-conscience-de-la-menace-du-sida-dans-le-pays\/"},"modified":"2014-08-15T13:40:01","modified_gmt":"2014-08-15T13:40:01","slug":"sante-le-nigeria-prend-conscience-de-la-menace-du-sida-dans-le-pays","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/francais\/2014\/08\/15\/sante-le-nigeria-prend-conscience-de-la-menace-du-sida-dans-le-pays\/","title":{"rendered":"SANTE: Le Nigeria prend conscience de la menace du SIDA dans le pays"},"content":{"rendered":"<p>LAGOS, Nigeria, 15 ao\u00fbt (IPS) &#8211; Le mariage de Tope Tayo a pris fin il y a 11 ans apr\u00e8s que son test pour le VIH s\u2019est r\u00e9v\u00e9l\u00e9 positif. Son mari en col\u00e8re et embarrass\u00e9 a emmen\u00e9 avec lui leur enfant unique. Trois mois plus tard, lorsque le gar\u00e7on \u00e2g\u00e9 d&#39;un an a \u00e9t\u00e9 d\u00e9clar\u00e9 s\u00e9ropositif, le mari l\u2019a ramen\u00e9 \u00e0 Tayo et s&#39;est enfui.\n <\/p>\n<p><!--more--><\/p>\n<p>&#8220;Il nous a abandonn\u00e9s comme si nous avions commis un crime, mais je lui ai dit que le VIH n&#39;est pas un crime&#8221;, a d\u00e9clar\u00e9 Tayo \u00e0 IPS.<\/p>\n<p> Elle \u00e9tait sans emploi et le mari ne payait aucune somme pour l\u2019entretien. &#8220;Je marchais dans les rues en pleurant, je vivais de la charit\u00e9&#8221;, se souvient Tayo.<\/p>\n<p> L&#39;homme fugitif qui abandonne sa femme et ses enfants s\u00e9ropositifs est une personnalit\u00e9 bien connue au Nigeria, affirme Rosemary Hua, coordonnatrice de &#39;First Step Action for Children&#39;, une organisation qui d\u00e9fend les droits de l&#39;enfant.<\/p>\n<p> &#8220;Les p\u00e8res retirent leur soutien parce qu\u2019ils estiment qu&#39;il n&#39;est pas n\u00e9cessaire d&#39;investir dans un enfant qui susceptible de mourir jeune&#8221;, a indiqu\u00e9 Hua \u00e0 IPS.<\/p>\n<p> Le taux d&#39;infection au VIH au Nigeria de 3,2 pour cent semble faible par rapport \u00e0 l&#39;Afrique australe, mais avec une population de 173 millions d\u2019habitants, cela signifie un tr\u00e8s grand nombre &#8211; 3,4 millions de Nig\u00e9rians vivaient avec le VIH en 2013.<\/p>\n<p> Parmi ceux-ci, 430.000 sont des enfants de moins de 14 ans, selon un r\u00e9cent rapport du Programme conjoint des Nations Unies sur le VIH\/SIDA (ONUSIDA). Le Nigeria repr\u00e9sente un tiers de toutes les nouvelles infections chez les enfants dans les 20 pays les plus touch\u00e9s en Afrique subsaharienne.<\/p>\n<p> Le rapport indique que le Nigeria est confront\u00e9 \u00e0 &#8220;la triple menace de la hausse de la charge du VIH, de la faiblesse de la couverture de traitement et de peu ou pas de baisse des nouvelles infections au VIH&#8221;.<\/p>\n<p> Pourquoi des femmes \u00e9vitent de faire le test  Tayo et son fils prennent des m\u00e9dicaments antir\u00e9troviraux depuis les 11 derni\u00e8res ann\u00e9es. Ils ont de la chance. Moins de 600.000 Nig\u00e9rians sont sous traitement, soit 20 pour cent de ceux qui en ont besoin.<\/p>\n<p> La faiblesse de la couverture de traitement perp\u00e9tue les id\u00e9es fausses et la stigmatisation, comme le montre l&#39;histoire de Tayo.<\/p>\n<p> L\u2019abandon se traduit g\u00e9n\u00e9ralement par des difficult\u00e9s \u00e9conomiques. La moiti\u00e9 des femmes sont au ch\u00f4mage au Nigeria.<\/p>\n<p> &#8220;Le d\u00e9sespoir de prendre soin d&#39;elle-m\u00eame et de son enfant pourrait pousser une femme s\u00e9ropositive dans des activit\u00e9s sexuelles afin de r\u00e9unir de l&#39;argent et cela pourrait propager davantage le VIH&#8221;, explique Lucy Attah, une activiste de genre vivant avec le VIH. Elle est la directrice ex\u00e9cutive de &#39;Women and Children of Hope Foundation&#39;, qui aide les femmes s\u00e9ropositives, et o\u00f9 IPS a rencontr\u00e9 Tayo.<\/p>\n<p> Tayo a d\u00e9clar\u00e9 \u00e0 IPS qu&#39;elle \u00e9vitait le d\u00e9pistage du VIH pendant qu\u2019elle \u00e9tait enceinte. Les h\u00f4pitaux publics au Nigeria font le d\u00e9pistage syst\u00e9matique des femmes enceintes, mais la peur de la discrimination au cas o\u00f9 le test se r\u00e9v\u00e8le positif a conduit Tayo vers un h\u00f4pital priv\u00e9 o\u00f9 le d\u00e9pistage n&#39;\u00e9tait pas requis.<\/p>\n<p> &#8220;C&#39;est le plus grand regret de ma vie&#8221;, a-t-elle indiqu\u00e9 \u00e0 IPS.<\/p>\n<p> Une raison pour laquelle les femmes enceintes \u00e9vitent de faire le test, indique Hua, c\u2019est le &#8220;manque de professionnalisme en ne gardant pas confidentiels les r\u00e9sultats [du test de d\u00e9pistage] du VIH&#8221;, de la part des agents de sant\u00e9.<\/p>\n<p> &#8220;Parfois, nous \u00e9tions oblig\u00e9s de transf\u00e9rer les malades vers d&#39;autres h\u00f4pitaux loin de l\u00e0 o\u00f9 ils vivent en raison de la divulgation de leur statut s\u00e9rologique&#8221;, a-t-elle soulign\u00e9 \u00e0 IPS.<\/p>\n<p> Certains agents de sant\u00e9 \u00e9vitent tout contact avec les femmes s\u00e9ropositives parce qu&#39;ils croient \u00e0 tort qu&#39;ils peuvent contracter le virus par simple toucher, explique Attah.<\/p>\n<p> &#8220;En surface, il semble qu&#39;il y existe beaucoup de sensibilisation parmi les agents de sant\u00e9, mais en r\u00e9alit\u00e9, il y a beaucoup de stigmatisation&#8221;, indique Attah.<\/p>\n<p> Une loi anti-discrimination et sur la confidentialit\u00e9 a \u00e9t\u00e9 approuv\u00e9e par les deux chambres et attend la signature du pr\u00e9sident Goodluck Jonathan.<\/p>\n<p> Mais le Nigeria a besoin de plus de lois pour faire face \u00e0 l&#39;\u00e9pid\u00e9mie.<\/p>\n<p> En 2012, l&#39;ONUSIDA a qualifi\u00e9 la r\u00e9ponse du pays de &#8220;stagnante&#8221; qui exige &#8220;un effort massif&#8221;.<\/p>\n<p> Le Nigeria repr\u00e9sente 13 pour cent de toutes les personnes vivant avec le VIH et 19 pour cent de tous les d\u00e9c\u00e8s li\u00e9s au SIDA en Afrique subsaharienne, selon l&#39;ONUSIDA.<\/p>\n<p> Seulement le Tchad occupe une place inf\u00e9rieure \u00e0 celle du Nigeria en mati\u00e8re de la couverture du traitement des femmes enceintes s\u00e9ropositives.<\/p>\n<p> Quelques bonnes nouvelles Depuis cette description accablante, le gouvernement a pris des mesures audacieuses pour r\u00e9duire la Pr\u00e9vention de la transmission de la m\u00e8re \u00e0 l&#39;enfant (PTME) dans les 12 Etats les plus touch\u00e9s.<\/p>\n<p> La couverture de la PTME est pass\u00e9e \u00e0 27 pour cent en 2013, une augmentation consid\u00e9rable \u00e0 partir de 19 pour cent en 2012, selon le Fonds des Nations Unies pour l&#39;enfance (UNICEF).<\/p>\n<p> Certains Etats ont doubl\u00e9 ou tripl\u00e9 le nombre de centres de sant\u00e9 qui offrent les services li\u00e9s au VIH, portant le nombre de sites de PTME \u00e0 2.216 &#8211; encore loin des 16.400 requis pour une couverture ad\u00e9quate.<\/p>\n<p> Le nombre de nouvelles infections par an chez les enfants a baiss\u00e9, de 60.000 en 2012 \u00e0 51.000 en 2013.<\/p>\n<p> Mais, avec deux femmes enceintes sur trois fuyant les soins pr\u00e9natals, le d\u00e9fi sera de les atteindre gr\u00e2ce \u00e0 l&#39;am\u00e9lioration des services et la sensibilisation.<\/p>\n<p> &#8220;Nous devons aller vers elles au lieu d&#39;attendre qu&#39;elles viennent au centre de sant\u00e9&#8221;, a d\u00e9clar\u00e9 \u00e0 IPS, Arjan de Wagt, charg\u00e9 des enfants et du VIH \u00e0 l&#39;UNICEF au Nigeria. &#8220;Sinon, les enfants continueront de mourir du SIDA inutilement&#8221;.<\/p>\n<p> Edit\u00e9 par Mercedes Sayagues Traduit en fran\u00e7ais par Roland Kocouvi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAGOS, Nigeria, 15 ao\u00fbt (IPS) &#8211; Le mariage de Tope Tayo a pris fin il y a 11 ans apr\u00e8s que son test pour le VIH s\u2019est r\u00e9v\u00e9l\u00e9 positif. Son mari en col\u00e8re et embarrass\u00e9 a emmen\u00e9 avec lui leur&hellip; <a href=\"http:\/\/ipsnews.net\/francais\/2014\/08\/15\/sante-le-nigeria-prend-conscience-de-la-menace-du-sida-dans-le-pays\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":283,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11,10,6,2,1,7,3,4,21,30,29],"tags":[],"class_list":["post-7017","post","type-post","status-publish","format-standard","hentry","category-afrique","category-developpement","category-droits-humains","category-economie-finances-le-commerce","category-education","category-headlines","category-politique","category-population-refugies","category-sante","category-science-technologie","category-special-culture-religion-et-genre","category-west-africa"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/7017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=7017"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/7017\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=7017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=7017"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=7017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}