{"id":4176,"date":"2008-12-06T13:40:01","date_gmt":"2008-12-06T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2008\/12\/06\/medias-rd-congo-assassinats-de-journalistes-et-parodies-de-justice\/"},"modified":"2008-12-06T13:40:01","modified_gmt":"2008-12-06T13:40:01","slug":"medias-rd-congo-assassinats-de-journalistes-et-parodies-de-justice","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/francais\/2008\/12\/06\/medias-rd-congo-assassinats-de-journalistes-et-parodies-de-justice\/","title":{"rendered":"MEDIAS-RD CONGO: Assassinats de journalistes et parodies de justice"},"content":{"rendered":"<p>KINSHASA, 6 d\u00e9c (IPS) &#8211; Depuis l&#39;homicide de Frank Kangundu, journaliste du quotidien congolais &#39;La R\u00e9f\u00e9rence Plus&#39; et de son \u00e9pouse H\u00e9l\u00e8ne Paka, en novembre 2004, la R\u00e9publique d\u00e9mocratique du Congo (RDC) est entr\u00e9e dans un triste cycle d&#39;assassinats de professionnels des m\u00e9dias.<\/p>\n<p><!--more--><\/p>\n<p>Le dernier assassinat en date est celui de Didace Namujimbo, journaliste \u00e0 Radio Okapi, abattu d&#39;une balle \u00e0 la t\u00eate par des inconnus dans la nuit du 21 au 22 novembre 2008 pr\u00e8s de son domicile, au quartier Ndendere dans la commune d&#39;Ibanda \u00e0 Bukavu, dans la province du Sud-Kivu (est de la RDC).<\/p>\n<p> Les cinq journalistes ont trouv\u00e9 la mort depuis quatre ans dans des circonstances quasi-similaires laissant ainsi soup\u00e7onner des assassinats commandit\u00e9s et non des crimes crapuleux comme l&#39;affirment certains, notamment Lambert Mende, ministre de la Communication et des M\u00e9dias, parlant de l&#39;assassinat de Namujimbo.  Seul Mutombo Kayilu, technicien de maintenance des \u00e9metteurs \u00e0 la &#39;Renatelsat&#39;, a \u00e9t\u00e9 tu\u00e9 au poignard le 29 mars 2006 sur le site de Kisanga, une bourgade situ\u00e9e au sud de Lubumbashi, dans la province du Katanga (sud-est), alors que tous les autres ont \u00e9t\u00e9 tu\u00e9s par balles tir\u00e9es \u00e0 bout portant.  Selon certains analystes, Mutombo aurait \u00e9t\u00e9 une victime de la crise politique de mars 2006 aliment\u00e9e par la contestation, par le Mouvement pour la lib\u00e9ration du Congo (MLC de Jean-Pierre Bemba), des r\u00e9sultats du second tour de la pr\u00e9sidentielle remport\u00e9e par Joseph Kabila au d\u00e9triment de Bemba, candidat malheureux. Ce qui avait provoqu\u00e9 des affrontements militaires, les 22 et 23 mars, entre les soldats respectivement commis \u00e0 la garde de deux challengers. Ensuite, Mutombo a \u00e9t\u00e9 assassin\u00e9 le m\u00eame jour o\u00f9 ont \u00e9t\u00e9 sabot\u00e9s les \u00e9metteurs de la cha\u00eene de t\u00e9l\u00e9vision priv\u00e9e Canal Congo t\u00e9l\u00e9vision appartenant \u00e0 Bemba.<\/p>\n<p> Bapua Mwamba est le troisi\u00e8me journaliste assassin\u00e9, abattu en 2006.  Hormis le cas de Franck Kangundu, l&#39;insolite est que les biens que les victimes portaient sur elles n&#39;ont jamais \u00e9t\u00e9 touch\u00e9s, comme le souligne l&#39;organisation de d\u00e9fense de la libert\u00e9 de la presse &#39;Journaliste en danger&#39; (JED), battant en br\u00e8che l&#39;hypoth\u00e8se de crimes crapuleux. Seul son t\u00e9l\u00e9phone portable avait \u00e9t\u00e9 arrach\u00e9 \u00e0 Kangundu, laissant na\u00eetre des doutes sur le vrai mobile du meurtre. Pourtant, les criminels avaient toute la possibilit\u00e9 de s&#39;emparer, au minimum, de sa voiture Mercedes noire, abandonn\u00e9e sur le lieu du crime, selon Djudju et Francine Kangundu, deux enfants du disparu.  En outre, ces assassinats se sont toujours perp\u00e9tr\u00e9s \u00e0 l&#39;occasion ou pendant des circonstances politiques et s\u00e9curitaires particuli\u00e8res au point de laisser croire qu&#39;ils y sont de pr\u00e8s ou de loin rattach\u00e9s.  L&#39;assassinat de Franck Kangundu et de son \u00e9pouse, est intervenu pendant une forte crise politique aliment\u00e9e par des all\u00e9gations qui faisaient \u00e9tat d&#39;un don de 30 millions de dollars par le pr\u00e9sident congolais Joseph Kabila au syst\u00e8me \u00e9ducatif tanzanien, cr\u00e9ant ainsi un remous. Cette p\u00e9riode \u00e9tait \u00e9galement caract\u00e9ris\u00e9e par des revendications sociales multiples pour de meilleures conditions salariales notamment pour les enseignants, selon un rapport de JED.<\/p>\n<p> Les assassinats de Serge Maheshe et de Didace Namujimbo de Radio Okapi &#8212; un projet conjoint de la Fondation Hirondelle et de la Mission des Nations Unies au Congo (MONUC) &#8212; sont survenus pendant que l&#39;est de la RDC \u00e9tait crisp\u00e9 par des informations faisant \u00e9tat d&#39;un complot concoct\u00e9 \u00e0 Kigali, au Rwanda, pour une nouvelle attaque contre le pays, avec la complicit\u00e9 de quelques autorit\u00e9s congolaises et du Congr\u00e8s national pour la d\u00e9fense du peuple (CNDP) du rebelle Laurent Nkunda. &#8220;Serge et Didace auraient-ils eu vent de ces informations devenant, par le fait, des cibles?&#8221;, se demandent toujours plusieurs activistes des droits de l&#39;Homme.  Par ailleurs, les cinq professionnels des m\u00e9dias ont \u00e9t\u00e9 tu\u00e9s par ou en pr\u00e9sence d&#39;hommes en armes, \u00e0 proximit\u00e9 de postes de police qui ne sont jamais intervenus, malgr\u00e9 les bruits des coups de balles. Et les criminels pr\u00e9sum\u00e9s ont souvent \u00e9t\u00e9 rattrap\u00e9s quelques heures seulement apr\u00e8s le forfait, puis d\u00e9f\u00e9r\u00e9s devant des tribunaux militaires, alors qu&#39;il existe des passerelles l\u00e9gales donnant comp\u00e9tence aux juridictions civiles pour ces meurtres.<\/p>\n<p> &#8220;Nous allons nous impliquer pour que la justice fasse r\u00e9ellement son travail et rende la justice aux victimes&#8221;, ont chaque fois promis des responsables politiques et judiciaires parmi lesquels Azarias Ruberwa, alors vice-pr\u00e9sident de la R\u00e9publique en charge notamment du secteur judiciaire lors de l&#39;assassinat de Franck Kangundu.  Les m\u00eames propos \u00e9taient tenus \u00e9galement par Aunorius Kisimba Ngoy, ministre de la Justice lors de l&#39;assassinat de Serge Maheshe, ou encore par Charles Mwando Nsimba, l&#39;actuel ministre de la D\u00e9fense, qui se dit &#8220;pr\u00eat \u00e0 s&#39;impliquer pour que la v\u00e9rit\u00e9 sur cet assassinat (de Didace Namujimbo) \u00e9clate au grand jour&#8221;.  Rien ne laisse croire que le proc\u00e8s en cours conna\u00eetra un sort diff\u00e9rent. Tous les proc\u00e8s cl\u00f4tur\u00e9s n&#39;ont \u00e9t\u00e9 que des parodies de justice. JED et l&#39;UNPC (Union nationale de la presse du Congo) d\u00e9noncent des poursuites contre des auteurs pr\u00e9sum\u00e9s dont la culpabilit\u00e9 est demeur\u00e9e non-\u00e9tablie, des enqu\u00eates jamais termin\u00e9es et controvers\u00e9es ainsi que des d\u00e9cisions complaisantes. Ces affirmations sont contenues dans un m\u00e9morandum conjoint sign\u00e9 par neuf organisations de la soci\u00e9t\u00e9 civile congolaise, adress\u00e9 \u00e0 Dieudonn\u00e9 Kayembe, chef d&#39;\u00e9tat-major g\u00e9n\u00e9ral des Forces arm\u00e9es congolaises, le 27 juin 2007.<\/p>\n<p> Puisque des enqu\u00eates b\u00e2cl\u00e9es ne peuvent produire qu&#39;un simulacre de proc\u00e8s qui ne ferait qu&#39;alimenter l&#39;impunit\u00e9, les organisations de la soci\u00e9t\u00e9 civile ont recommand\u00e9 \u00e0 l&#39;autorit\u00e9 de donner des moyens mat\u00e9riels et l&#39;ind\u00e9pendance n\u00e9cessaires \u00e0 la justice pour conduire des enqu\u00eates professionnelles et des proc\u00e8s justes et \u00e9quitables, sans exclure aucune piste, d\u00e9clare Chantal Kanyimbo, pr\u00e9sidente de l&#39;UNPC.<\/p>\n<p> Les trois proc\u00e8s, qui ont eu lieu sur des assassinats de journalistes avant 2008, n&#39;ont pas pu lever toutes les zones d&#39;ombre par rapport aux mobiles, aux auteurs et aux commanditaires de ces meurtres pour la simple raison que les enqu\u00eates pr\u00e9liminaires ont \u00e9t\u00e9 sciemment b\u00e2cl\u00e9es, selon JED. Et le cycle de violence qui vise les journalistes se nourrit de l&#39;impunit\u00e9 assur\u00e9e aux v\u00e9ritables assassins et commanditaires au travers des simulacres de proc\u00e8s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KINSHASA, 6 d\u00e9c (IPS) &#8211; Depuis l&#39;homicide de Frank Kangundu, journaliste du quotidien congolais &#39;La R\u00e9f\u00e9rence Plus&#39; et de son \u00e9pouse H\u00e9l\u00e8ne Paka, en novembre 2004, la R\u00e9publique d\u00e9mocratique du Congo (RDC) est entr\u00e9e dans un triste cycle d&#39;assassinats de&hellip; <a href=\"http:\/\/ipsnews.net\/francais\/2008\/12\/06\/medias-rd-congo-assassinats-de-journalistes-et-parodies-de-justice\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":635,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,5,24,10,1,7],"tags":[],"class_list":["post-4176","post","type-post","status-publish","format-standard","hentry","category-africa-centrale","category-afrique","category-communication-medias","category-droits-humains","category-headlines","category-politique"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/4176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/635"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=4176"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/4176\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=4176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=4176"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=4176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}