{"id":3194,"date":"2006-11-15T13:40:01","date_gmt":"2006-11-15T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2006\/11\/15\/poltique-maroc-et-si-on-reduisait-un-peu-les-prerogatives-du-roi\/"},"modified":"2006-11-15T13:40:01","modified_gmt":"2006-11-15T13:40:01","slug":"poltique-maroc-et-si-on-reduisait-un-peu-les-prerogatives-du-roi","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/francais\/2006\/11\/15\/poltique-maroc-et-si-on-reduisait-un-peu-les-prerogatives-du-roi\/","title":{"rendered":"POLTIQUE-MAROC: Et si on r\u00e9duisait un peu les pr\u00e9rogatives du roi!"},"content":{"rendered":"<p>RABAT, 15 nov (IPS) &#8211; Les Marocains sont engag\u00e9s actuellement dans un d\u00e9bat sur la possibilit\u00e9 de r\u00e9duire les pr\u00e9rogatives constitutionnelles de leur roi. Et chacun des diff\u00e9rents acteurs politiques du royaume y va de ses arguments, mais aussi de ses int\u00e9r\u00eats.<\/p>\n<p><!--more--><\/p>\n<p>Le ballet a \u00e9t\u00e9 ouvert \u00e0 l&#39;initiative d&#39;un collectif d&#39;organisations non gouvernementales (ONG), qui a rendu public, dans la presse, un appel intitul\u00e9 &#8220;Pour une nouvelle constitution qui s&#39;applique&#8221;. Si la r\u00e9duction des pr\u00e9rogatives du roi n&#39;est pas explicitement \u00e9voqu\u00e9e, les notions de &#8220;r\u00e9partition et d&#39;\u00e9quilibre des pouvoirs&#8221; y trouvent un grand \u00e9cho.<\/p>\n<p> &#8220;Les exigences de l&#39;action r\u00e9formatrice&#8230;plaident, d&#39;une part pour un gouvernement plus autonome et aux pr\u00e9rogatives renforc\u00e9es dans la d\u00e9termination et la conduite de la politique g\u00e9n\u00e9rale; d&#39;autre part, pour un d\u00e9veloppement des moyens d&#39;action du parlement en termes d&#39;investigation, d&#39;interpellation et de contr\u00f4le de l&#39;ex\u00e9cutif&#8221;, souligne l&#39;appel qui \u00e9voque \u00e9galement &#8220;l&#39;affirmation d&#39;un pouvoir judiciaire ind\u00e9pendant&#8221;.<\/p>\n<p> Azzedine Akesbi, un universitaire r\u00e9sidant \u00e0 Casablanca, dans le nord-ouest du pays, est le repr\u00e9sentant de &#39;Transparency Maroc&#39;, l&#39;une des ONG signataires de cet appel. Il estime qu&#39;\u00e0 partir de la th\u00e9matique qui pr\u00e9occupe son organisation &#8212; la corruption &#8211;, &#8220;nous nous sommes but\u00e9s sur des probl\u00e8mes de gouvernance qui requi\u00e8rent n\u00e9cessairement des institutions ind\u00e9pendantes et responsables, d&#39;o\u00f9 la n\u00e9cessit\u00e9 d&#39;une r\u00e9forme constitutionnelle&#8221;. (Transparency Maroc est la section marocaine de &#39;Transparency International&#39; bas\u00e9e \u00e0 Berlin).  Ceci nous am\u00e8ne, dit-il \u00e0 IPS, \u00e0 souligner qu&#39;il y a un besoin pressant au Maroc de clarifier les r\u00f4les de chaque institution s\u00e9par\u00e9ment, afin de d\u00e9terminer les responsabilit\u00e9s de tout acteur politique, quel que soit son rang. &#8220;Il est temps que tout le monde soit responsable de ses actes politiques&#8221;, ajoute Akesbi.   Pour Akesbi et d\u2019autres intellectuels marocains, parler au Maroc de l&#39;\u00e9quilibre des pouvoirs ou de la responsabilisation de tous les acteurs politiques, revient \u00e0 situer clairement la place de l&#39;institution monarchique dans l&#39;\u00e9chiquier politique national.   Selon Mohamed Sebbar, pr\u00e9sident du Forum v\u00e9rit\u00e9 et justice, un mouvement compos\u00e9 des anciens d\u00e9tenus et victimes des violations des droits humains sous le r\u00e8gne de l\u2019ancien roi Hassan II, &#8220;il existe dans la constitution actuelle une concentration des pouvoirs dans les mais du monarque&#8221;.<\/p>\n<p> Et cet avocat explique \u00e0 IPS que l&#39;article 19 de la constitution refl\u00e8te le plus cette concentration, puisque cette disposition stipule que le roi peut exercer le pouvoir ex\u00e9cutif, \u00eatre \u00e0 la t\u00eate du Conseil de la magistrature, l\u00e9gif\u00e9rer entre les deux sessions parlementaires, nommer les hauts fonctionnaires, les officiers, les ambassadeurs, et peut aussi prononcer l&#39;\u00e9tat d&#39;exception.<\/p>\n<p> Si les ONG empruntent un d\u00e9tour plus ou moins euph\u00e9mique, certains hommes politiques marocains ne m\u00e2chent pas leurs mots. L&#39;objectif, pour eux, reste une r\u00e9duction des pouvoirs de l&#39;institution monarchique au profit des autres institutions, celles qui sont \u00e9lues notamment.<\/p>\n<p> &#8220;Les r\u00e9formes politiques attendues devraient aller dans le sens de r\u00e9duire les pr\u00e9rogatives du roi, pour renforcer les pouvoirs du gouvernement, de la Chambre des d\u00e9put\u00e9s&#8221;, a d&#39;embl\u00e9e d\u00e9clar\u00e9 \u00e0 IPS, Ahmed Sbai, d\u00e9put\u00e9 et membre du bureau politique du Parti socialiste unifi\u00e9 (PSU) &#8212; un parti d&#39;opposition de gauche, compos\u00e9 de plusieurs groupes de la gauche unifi\u00e9e ces deux derni\u00e8res ann\u00e9es dans ce pays d&#39;Afrique du nord.<\/p>\n<p> L&#39;objectif, selon Sbai qui est d\u00e9put\u00e9 de l&#39;une des circonscriptions du Maroc oriental, est de &#8220;parvenir \u00e0 un \u00e9quilibre entre les diff\u00e9rentes institutions politiques au Maroc et de r\u00e9aliser, par cons\u00e9quent, une r\u00e9elle transition d\u00e9mocratique&#8221;.  En fait, le d\u00e9bat porte \u00e9galement sur un antagonisme qu&#39;\u00e9tablissent les d\u00e9fenseurs de cette th\u00e8se entre l&#39;expression de la volont\u00e9 populaire, d&#39;une part, et les pouvoirs constitutionnels et extra-constitutionnels de l&#39;institution monarchique, d&#39;autre part.<\/p>\n<p> Pour Sbai, du moment que le gouvernement et le parlement \u00e9manent de la volont\u00e9 populaire exprim\u00e9e \u00e0 travers des \u00e9lections, il est imp\u00e9ratif qu&#39;ils aient des pr\u00e9rogatives claires et \u00e9largies permettant au premier d&#39;appliquer son programme et d&#39;assumer sa responsabilit\u00e9 \u00e0 cet \u00e9gard, et au second d&#39;exercer son r\u00f4le de contr\u00f4le de l&#39;action de l&#39;ex\u00e9cutif.<\/p>\n<p> En r\u00e9alit\u00e9, le PSU de Sbai vise, au plan strat\u00e9gique, \u00e0 aboutir \u00e0 une monarchie parlementaire, o\u00f9 le roi r\u00e8gne mais ne gouverne pas. Ceci n\u00e9cessite, sur le plan pratique, le renforcement de l&#39;institution du Premier ministre et le Conseil du gouvernement, au lieu d&#39;un Conseil des ministres pr\u00e9sid\u00e9 par le roi.  Par contre, les partis politiques d\u00e9mocratiques traditionnels prenant part au gouvernement actuel, ne voient aucune n\u00e9cessit\u00e9 de la r\u00e9duction des pr\u00e9rogatives royales.  Membre dirigeant du Parti du progr\u00e8s et du socialisme &#8212; ancien parti communiste &#8212; Khalid Naciri, estime &#8220;qu&#39;il ne s&#39;agit pas de r\u00e9duire les pr\u00e9rogatives royales&#8230;dans la mesure o\u00f9 la question constitutionnelle se r\u00e9sume en une meilleure rationalisation des m\u00e9canismes du pouvoir&#8221;.  Naciri a d\u00e9clar\u00e9 \u00e0 IPS que &#8220;l&#39;essentiel consiste en une meilleure articulation des pouvoirs constitutionnels du roi, du gouvernement et du parlement, pour un Etat plus d\u00e9mocratique, plus fort et plus efficace&#8221;. Pour luii, &#8220;Le roi doit demeurer l&#39;instance dot\u00e9e de la l\u00e9gitimit\u00e9 historique et politique qui est la sienne&#8221;. Mais, ajoute-t-il, il faut \u2018\u2019accorder un statut constitutionnel plus visible aux engagements internationaux du Maroc en mati\u00e8re des droits de l&#39;Homme&#8221;.<\/p>\n<p> Se fondant sur la sp\u00e9cificit\u00e9 du syst\u00e8me politique marocain et le r\u00e9alisme politique, Najib Ba Mohamed, professeur de droit \u00e0 l&#39;Universit\u00e9 de F\u00e8s, dans le centre-nord du pays, explique que &#8220;l&#39;histoire de la r\u00e9vision constitutionnelle est bien celle de la recherche d&#39;un pacte constitutionnel n\u00e9goci\u00e9 entre la monarchie et les forces politiques, mais les temps ont chang\u00e9 et les Marocains sont de plus en plus exigeants&#8221;.<\/p>\n<p> Selon Mohamed, la r\u00e9ussite d&#39;une constitution d\u00e9pend n\u00e9anmoins, en grande partie, du consensus qui l&#39;entoure, lequel, souligne-t-il, &#8220;requiert plus de clart\u00e9 et de transparence de la part de la classe politique appel\u00e9e \u00e0 rel\u00e9guer les calculs et les man\u0153uvres politiques ou politiciennes pour plus de cr\u00e9ativit\u00e9 et de r\u00e9alisme politique&#8221;.  Autres pr\u00e9occupations, autres visions. Ahmed Arehmouch, avocat \u00e0 Rabat, la capitale marocaine, et son ONG qui lutte pour les droits linguistiques et culturels, le &#8220;R\u00e9seau amazigh&#8221;, estiment que le d\u00e9bat sur la constitution ne devrait pas cibler uniquement le paradigme de &#8220;la s\u00e9paration des pouvoirs&#8221;.  Pour lui, cette d\u00e9marche, suppos\u00e9e garantir une transition vers un r\u00e9gime politique parlementaire dans le royaume, &#8220;\u00e9vacue le paradigme des &#39;droits et libert\u00e9s&#39;, qui fonde l&#39;ensemble de la perception, par le mouvement \u2018amazigh\u2019, du texte constitutionnel et de l&#39;op\u00e9ration visant \u00e0 constitutionnaliser des droits culturels et linguistiques&#8221;.  Le mouvement \u2018amazigh\u2019 marocain comprend un tissu associatif d\u00e9fendant les droits culturels et linguistiques de la communaut\u00e9 &#8220;berberophone&#8221; ou berb\u00e8re, et revendiquant la constitutionnalisation de la langue amazighe en tant que langue officielle, sur le m\u00eame pied d\u2019\u00e9galit\u00e9 que l\u2019arabe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RABAT, 15 nov (IPS) &#8211; Les Marocains sont engag\u00e9s actuellement dans un d\u00e9bat sur la possibilit\u00e9 de r\u00e9duire les pr\u00e9rogatives constitutionnelles de leur roi. Et chacun des diff\u00e9rents acteurs politiques du royaume y va de ses arguments, mais aussi de&hellip; <a href=\"http:\/\/ipsnews.net\/francais\/2006\/11\/15\/poltique-maroc-et-si-on-reduisait-un-peu-les-prerogatives-du-roi\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":388,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,13,10,1,7],"tags":[],"class_list":["post-3194","post","type-post","status-publish","format-standard","hentry","category-afrique","category-culture-religion-sport","category-droits-humains","category-headlines","category-politique"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/3194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/388"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=3194"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/3194\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=3194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=3194"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=3194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}