{"id":2251,"date":"2004-09-16T13:40:01","date_gmt":"2004-09-16T13:40:01","guid":{"rendered":"http:\/\/ipsnews.net\/francais\/2004\/09\/16\/politique-cameroun-le-debat-sur-linformatisation-du-processus-electoralprovoque-des-tensions\/"},"modified":"2004-09-16T13:40:01","modified_gmt":"2004-09-16T13:40:01","slug":"politique-cameroun-le-debat-sur-linformatisation-du-processus-electoralprovoque-des-tensions","status":"publish","type":"post","link":"http:\/\/ipsnews.net\/francais\/2004\/09\/16\/politique-cameroun-le-debat-sur-linformatisation-du-processus-electoralprovoque-des-tensions\/","title":{"rendered":"POLITIQUE-CAMEROUN: Le d\u00e9bat sur l&#39;informatisation du processus \u00e9lectoralprovoque des tensions"},"content":{"rendered":"<p>YAOUNDE, 16 sep (IPS) &#8211; L&#39;\u00e9lection pr\u00e9sidentielle au Cameroun est pr\u00e9vue le 11 octobre. Mais d\u00e9j\u00e0, le climat social et politique conna\u00eet des tensions qui opposent les partis politiques de l&#39;opposition au gouvernement, laissant pr\u00e9sager des lendemains incertains.\n<\/p>\n<p><!--more--><\/p>\n<p>\n La question de l&#39;informatisation dans le processus \u00e9lectoral de ce pays d&#39;Afrique centrale divise la classe politique, et est devenue, depuis juin dernier, le th\u00e8me majeur des manifestations de rues organis\u00e9es par les partis de l&#39;opposition.  &quot;Il faut absolument informatiser si on veut avoir une \u00e9lection transparente et cr\u00e9dible. Sans cela, au nom de l&#39;int\u00e9r\u00eat de notre pays, ce scrutin doit \u00eatre report\u00e9&quot;, a d\u00e9clar\u00e9 \u00e0 IPS, John Fru Ndi, pr\u00e9sident du Social Democratic Front (SDF), le principal parti de l&#39;opposition.<\/p>\n<p>&quot;Sinon&quot;, a-t-il ajout\u00e9, &quot;nous emp\u00eacherons la tenue du scrutin. Nous envahirons les rues afin de nous assurer que l&#39;\u00e9lection n&#39;aura pas lieu&quot;.<\/p>\n<p>L&#39;opposition parle d&#39;un report pour l&#39;ann\u00e9e prochaine, sans pr\u00e9ciser de date.<\/p>\n<p> Le d\u00e9bat sur l&#39;informatisation du processus \u00e9lectoral n&#39;est pas nouveau au Cameroun. Mais, il s&#39;est transform\u00e9 en des marches et meetings des partis de l&#39;opposition r\u00e9clamant l&#39;informatisation, qui se r\u00e9p\u00e8tent r\u00e9guli\u00e8rement \u00e0 Yaound\u00e9, la capitale politique, \u00e0 Douala, la capitale \u00e9conomique du pays, et dans d&#39;autres villes du pays, devenant une pr\u00e9occupation pour les Camerounais. Mais, en cette p\u00e9riode pr\u00e9-\u00e9lectorale, certains meetings des partis de l&#39;opposition tournent \u00e0 des \u00e9pisodes sanglants ou tragiques.  Le 20 ao\u00fbt, dans l&#39;arrondissement de Balikumbat, dans la province anglophone du Nord-Ouest situ\u00e9e \u00e0 quelque 400 kilom\u00e8tres de Yaound\u00e9, le pr\u00e9sident du district \u00e9lectoral du SDF, John Nkonteh, a \u00e9t\u00e9 tu\u00e9. Des partisans du Rassemblement d\u00e9mocratique du peuple camerounais (RDPC), le parti au pouvoir, et le chef &quot;Fon&quot; Doh Gah Gwanyin III, sont soup\u00e7onn\u00e9s d&#39;avoir commis ce meurtre. Gwanyin III est membre du Comit\u00e9 central du RDPC et d\u00e9put\u00e9 au parlement camerounais. Le 9 septembre, un communiqu\u00e9 officiel a annonc\u00e9 l&#39;arrestation de 11 suspects pour une &quot;instruction judiciaire cons\u00e9quente&quot;. Mais Gwanyin III est en libert\u00e9.<\/p>\n<p> En l&#39;absence de toute condamnation de ce meurtre par les autorit\u00e9s qui affirment mener encore l&#39;enqu\u00eate, le nord-ouest du pays vivait dans la psychose et sous des op\u00e9rations &quot;villes mortes&quot; r\u00e9clam\u00e9es par le SDF. Une exp\u00e9rience am\u00e8re pour des Camerounais.  Les premi\u00e8res villes mortes faisaient suite \u00e0 la mort de six personnes tu\u00e9es par la police, \u00e0 l&#39;occasion du meeting de lancement du SDF cr\u00e9\u00e9, en 1991 \u00e0 Bamenda, capitale provinciale du Nord-Ouest. On \u00e9tait encore sous le parti unique. Le climat politique s&#39;est alors d\u00e9t\u00e9rior\u00e9, aggrav\u00e9 par une crise \u00e9conomique aigu\u00eb. Le gouvernement a accept\u00e9 la cr\u00e9ation d&#39;autres partis politiques et plusieurs ont lanc\u00e9 une campagne de villes mortes qui ont paralys\u00e9 le pays, avec des manifestations tous les jeudis, r\u00e9clamant le d\u00e9part du pr\u00e9sident Paul Biya, au pouvoir depuis 1982.<\/p>\n<p> Au d\u00e9but ce mois, la Coalition nationale pour la reconstruction et la r\u00e9conciliation (CNRR) avait menac\u00e9 d&#39;organiser de violentes manifestations, le jour de l&#39;inhumation de Nkonteh. La plupart des quelque 200 partis politiques enregistr\u00e9s au Cameroun se r\u00e9clament de l&#39;opposition. Mais seuls trois sont repr\u00e9sent\u00e9s au parlement : le SDF, l&#39; UDC (Union d\u00e9mocratique du Cameroun), et l&#39;UNDP (Union nationale pour la d\u00e9mocratie et le progr\u00e8s).  Le jour de l&#39;enterrement de Nkonteh, un dispositif sp\u00e9cial de s\u00e9curit\u00e9 avait pris place aux premi\u00e8res heures de la matin\u00e9e pour, selon les autorit\u00e9s, &quot;pr\u00e9venir des actes de d\u00e9bordement \u00e9ventuels&quot;. Tout s&#39;est n\u00e9anmoins d\u00e9roul\u00e9 sans probl\u00e8mes, malgr\u00e9 la tension encore perceptible.<\/p>\n<p>Toutefois, les leaders de la CNRR, notamment Fru Ndi du SDF et Adamou Ndam Njoya de l&#39;UDC, ont fustig\u00e9, dans leur discours, le pouvoir, promettant d&#39;honorer la m\u00e9moire de Nkontheh par tous les moyens.  Pour les leaders de l&#39;opposition, l&#39;informatisation du processus est une occasion d&#39;en d\u00e9coudre pacifiquement avec le r\u00e9gime du pr\u00e9sident Biya. Elle pr\u00e9viendrait toutes sortes de d\u00e9rives. &quot;Nous savions, depuis, que la non-informatisation du processus \u00e9lectoral pourrait provoquer des d\u00e9rives incontr\u00f4lables&quot;, a dit \u00e0 IPS, Garga Haman Adji, pr\u00e9sident de l&#39;Alliance pour la d\u00e9mocratie et le d\u00e9veloppement (ADD).<\/p>\n<p> &quot;C&#39;est la raison pour laquelle, depuis au moins cinq ans, j&#39;avais fait la suggestion. L&#39;informatisation seule peut pr\u00e9server la paix sociale et garantir une \u00e9lection transparente&quot;, a-t-il ajout\u00e9.  Le gouvernement reconna\u00eet la n\u00e9cessit\u00e9 d&#39;informatiser le processus \u00e9lectoral. &quot;Ce serait un facteur de modernit\u00e9. Nous y accordons une attention minutieuse et nous voulons y associer tout le monde&#8230;, aller ailleurs chercher de l&#39;expertise et des comp\u00e9tences en invitant les autres \u00e0 un dialogue citoyen, franc\u00e0&quot;, avait d\u00e9clar\u00e9 le 27 ao\u00fbt \u00e0 la presse, Marafa Hamidou Yaya, ministre d&#39;Etat charg\u00e9 de l&#39;Administration territoriale et de la D\u00e9centralisation.  &quot;Notre v\u00e9ritable probl\u00e8me est la s\u00e9curisation des actes de naissance et de la Carte nationale d&#39;identit\u00e9&quot;, a dit \u00e0 IPS, Gr\u00e9goire Owona, secr\u00e9taire g\u00e9n\u00e9ral adjoint du RDPC et ministre charg\u00e9 des Relations avec le Parlement.  Le gouvernement estime qu&#39;il faudrait parachever d&#39;abord le processus de d\u00e9livrance des cartes nationales d&#39;identit\u00e9 informatis\u00e9es sans laquelle l&#39;informatisation du processus \u00e9lectoral ne peut \u00eatre possible.  &quot;Il faut que l&#39;informatisation soit per\u00e7ue comme un catalyseur de changement organisationnel et non comme un rem\u00e8de miracle&#8230; Nous sommes engag\u00e9s, mais le processus n\u00e9cessite la somme de 16 millions de dollars que nous n&#39;avons pas et aucun bailleur de fonds ne s&#39;est prononc\u00e9 pour nous aider&quot;, explique Owona.  Mais une source ayant requis l&#39;anonymat \u00e0 la Direction des affaires politiques du minist\u00e8re de l&#39;Administration territoriale, affirme que le gouvernement n&#39;a pas encore formul\u00e9 de demande de financement en direction des bailleurs de fonds. La m\u00eame source r\u00e9v\u00e8le que le gouvernement pourrait parvenir \u00e0 l&#39;informatisation \u00e0 partir des municipales et l\u00e9gislatives pr\u00e9vues en juin 2007.<\/p>\n<p> L&#39;opinion publique, pour sa part, appr\u00e9cie la question de fa\u00e7on divergente.<\/p>\n<p>&quot;Si le gouvernement ne veut pas l&#39;informatisation, c&#39;est qu&#39;il veut tout faire pour tricher comme d&#39;habitude&quot;, affirme, \u00e0 IPS, Paul Ngongang, informaticien et membre de Nouveaux droits de l&#39;Homme, une organisation non gouvernementale (ONG) bas\u00e9e \u00e0 Yaound\u00e9.  Ngongang ajoute : &quot;Certes, l&#39;informatisation n&#39;est pas susceptible de r\u00e9soudre les fraudes, mais on pourrait tenter cette exp\u00e9rience qui para\u00eet exaltante et qui a montr\u00e9 des voies de progr\u00e8s ailleurs&quot;.  Arlette Moukouri, membre du Programme int\u00e9gr\u00e9 de lutte contre la pauvret\u00e9, une ONG camerounaise, a dit \u00e0 IPS que &quot;l&#39;informatisation n&#39;est pas une potion magique&quot;. Selon elle, &quot;Le vrai probl\u00e8me, c&#39;est de s&#39;assurer que tous les Camerounais en \u00e2ge de voter ont des cartes d&#39;\u00e9lecteurs. Or la plupart des inscriptions en cours se font de mani\u00e8re s\u00e9lective par les commissions chapeaut\u00e9es par les sous-pr\u00e9fets. De la sorte, pensez-vous que l&#39;informatisation y fera quelque chose?&quot;, demande-t-elle.<\/p>\n<p> Des militants de l&#39;UDC ont d\u00e9clar\u00e9 \u00e0 IPS, le 13 septembre, que les listes \u00e9lectorales &quot;sont s\u00e9lectives pour la plupart, et que cela pourrait nuire aux chances de succ\u00e8s du candidat de l&#39;opposition&quot;. C&#39;est pour cette raison, expliquent-ils, que l&#39;opposition &quot;souhaite l&#39;informatisation de tout le processus&quot;.  Djeukam Tchameni, informaticien et pr\u00e9sident du Mouvement pour la d\u00e9mocratie et l&#39;interd\u00e9pendance (MDI), a d\u00e9clar\u00e9 \u00e0 IPS : &quot;Notre position est que ce sont\u00e0les conditions d&#39;organisation des \u00e9lections qui sont mauvaises au Cameroun. Il importe donc de les changer dans leur globalit\u00e9 et non partiellement&quot;.<\/p>\n<p> Mais il reconna\u00eet que &quot;L&#39;informatisation elle-m\u00eame n&#39;est pas susceptible de r\u00e9soudre le probl\u00e8me. Il ne faut pas transformer l&#39;informatisation en gris-gris qui apporte des solutions magiques&quot;.<\/p>\n<p> &quot;Concernant l&#39;\u00e9lection du 11 octobre, l&#39;informatisation est possible. On parle ici des listes \u00e9lectorales pour un maximum de huit millions d&#39;inscrits. A mon sens, on peut informatiser les listes \u00e9lectorales et les mettre \u00e0 la disposition de tous les Camerounais. Le blocage actuel n&#39;est donc pas un probl\u00e8me sur la faisabilit\u00e9 technique, mais une expression de la volont\u00e9 politique de ne pas \u00e9vacuer l&#39;environnement propice \u00e0 la fraude&quot;, a ajout\u00e9 Tchameni.  Le pr\u00e9sident Biya a annonc\u00e9 sa candidature mercredi soir, mais l&#39;opposition se pr\u00e9sente finalement en rangs dispers\u00e9s puisque Fru Ndi du SDF et Ndam Njoya de l&#39;UDC sont tous candidats.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>YAOUNDE, 16 sep (IPS) &#8211; L&#39;\u00e9lection pr\u00e9sidentielle au Cameroun est pr\u00e9vue le 11 octobre. Mais d\u00e9j\u00e0, le climat social et politique conna\u00eet des tensions qui opposent les partis politiques de l&#39;opposition au gouvernement, laissant pr\u00e9sager des lendemains incertains.<\/p>\n","protected":false},"author":253,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1,7],"tags":[],"class_list":["post-2251","post","type-post","status-publish","format-standard","hentry","category-afrique","category-headlines","category-politique"],"_links":{"self":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/users\/253"}],"replies":[{"embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/comments?post=2251"}],"version-history":[{"count":0,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/posts\/2251\/revisions"}],"wp:attachment":[{"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/media?parent=2251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/categories?post=2251"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ipsnews.net\/francais\/wp-json\/wp\/v2\/tags?post=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}